{"id":473,"date":"2026-07-05T17:56:32","date_gmt":"2026-07-05T15:56:32","guid":{"rendered":"https:\/\/alchimianarrante.eu\/presentation-at-wmf-2026\/"},"modified":"2026-07-05T18:11:30","modified_gmt":"2026-07-05T16:11:30","slug":"presentation-at-wmf-2026","status":"publish","type":"page","link":"https:\/\/alchimianarrante.eu\/en\/linfermiera-del-respiro\/presentation-at-wmf-2026\/","title":{"rendered":"Presentation at WMF 2026"},"content":{"rendered":"<style>.wp-block-kadence-spacer.kt-block-spacer-11_f77437-c6 .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-11_f77437-c6 .kt-divider{border-top-width:1px;height:1px;border-top-color:#e5dfd5;width:60%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-11_f77437-c6\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<style>.kb-row-layout-id27_hero-wmf > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id27_hero-wmf > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id27_hero-wmf > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:140px;padding-right:60px;padding-bottom:100px;padding-left:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id27_hero-wmf{background-color:#F6F2EC;}.kb-row-layout-id27_hero-wmf > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id27_hero-wmf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id27_hero-wmf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id27_hero-wmf alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column27_hero-wmf-col > .kt-inside-inner-col,.kadence-column27_hero-wmf-col > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column27_hero-wmf-col > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column27_hero-wmf-col > .kt-inside-inner-col{flex-direction:column;}.kadence-column27_hero-wmf-col > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column27_hero-wmf-col > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column27_hero-wmf-col{position:relative;}@media all and (max-width: 1024px){.kadence-column27_hero-wmf-col > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column27_hero-wmf-col > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column27_hero-wmf-col\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#C27A5A;font-size:11px;font-weight:500;letter-spacing:0.12em;text-transform:uppercase\">L&#8217;infermiera del respiro<\/p>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-text-color has-playfair-display-font-family\" style=\"color:#2B2B28;margin-top:12px;font-size:clamp(34px, 4.5vw, 52px);font-weight:400;line-height:1.25\">Presentation at WMF 2026<\/h1>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#5C5C55;margin-top:24px;font-size:clamp(17px, 1.8vw, 19px);font-style:italic;font-weight:300;line-height:1.7\">Bologna, June 24\u201326, 2026<\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id27_racconto > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id27_racconto > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id27_racconto > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:100px;padding-right:60px;padding-bottom:80px;padding-left:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id27_racconto{background-color:#FFFFFF;}.kb-row-layout-id27_racconto > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id27_racconto > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id27_racconto > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id27_racconto alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column27_racconto-col > .kt-inside-inner-col,.kadence-column27_racconto-col > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column27_racconto-col > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column27_racconto-col > .kt-inside-inner-col{flex-direction:column;}.kadence-column27_racconto-col > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column27_racconto-col > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column27_racconto-col{position:relative;}@media all and (max-width: 1024px){.kadence-column27_racconto-col > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column27_racconto-col > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column27_racconto-col\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#5C5C55;font-size:clamp(17px, 1.8vw, 19px);line-height:1.9\">From June 24 to 26, 2026, &#8220;L&#8217;infermiera del respiro&#8221; was presented at the Web Marketing Festival in Bologna, one of Italy&#8217;s most popular events for those working with content, communication, and digital storytelling.<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#5C5C55;margin-top:20px;font-size:clamp(17px, 1.8vw, 19px);line-height:1.9\">An opportunity to share, outside the healthcare context, the value of presence and listening\u2014and to introduce Alchimia Narrante&#8217;s editorial project to a new, curious, and diverse audience.<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#5C5C55;margin-top:20px;font-size:clamp(17px, 1.8vw, 19px);line-height:1.9\">Three days of meetings, conversations, and new faces\u2014a chapter added to the story of this book, beyond its pages.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id27_galleria > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id27_galleria > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id27_galleria > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:80px;padding-right:60px;padding-bottom:100px;padding-left:60px;}.kb-row-layout-id27_galleria > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id27_galleria > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id27_galleria{background-color:#F6F2EC;}.kb-row-layout-id27_galleria > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id27_galleria > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id27_galleria > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id27_galleria > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id27_galleria > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id27_galleria alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column27_foto-1 > .kt-inside-inner-col,.kadence-column27_foto-1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column27_foto-1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column27_foto-1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column27_foto-1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column27_foto-1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column27_foto-1{position:relative;}@media all and (max-width: 1024px){.kadence-column27_foto-1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column27_foto-1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column27_foto-1\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-large has-custom-border is-style-default\"><img decoding=\"async\" src=\"https:\/\/alchimianarrante.eu\/wp-content\/uploads\/2026\/07\/wmf-1.jpeg\" alt=\"WMF 2026 &#x2014; presentation of L'infermiera del respiro\" style=\"border-radius:4px\"\/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column27_foto-2 > .kt-inside-inner-col,.kadence-column27_foto-2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column27_foto-2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column27_foto-2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column27_foto-2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column27_foto-2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column27_foto-2{position:relative;}@media all and (max-width: 1024px){.kadence-column27_foto-2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column27_foto-2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column27_foto-2\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-large has-custom-border is-style-default\"><img decoding=\"async\" src=\"https:\/\/alchimianarrante.eu\/wp-content\/uploads\/2026\/07\/wmf-2.jpeg\" alt=\"WMF 2026 &#x2014; presentation of L'infermiera del respiro\" style=\"border-radius:4px\"\/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column27_foto-3 > .kt-inside-inner-col,.kadence-column27_foto-3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column27_foto-3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column27_foto-3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column27_foto-3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column27_foto-3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column27_foto-3{position:relative;}@media all and (max-width: 1024px){.kadence-column27_foto-3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column27_foto-3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column27_foto-3\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-large has-custom-border is-style-default\"><img decoding=\"async\" src=\"https:\/\/alchimianarrante.eu\/wp-content\/uploads\/2026\/07\/wmf-3.jpeg\" alt=\"WMF 2026 &#x2014; presentation of L'infermiera del respiro\" style=\"border-radius:4px\"\/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id27_chiusura-wmf > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id27_chiusura-wmf > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id27_chiusura-wmf > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:100px;padding-right:60px;padding-bottom:100px;padding-left:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id27_chiusura-wmf{background-color:#2B2B28;}.kb-row-layout-id27_chiusura-wmf > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id27_chiusura-wmf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id27_chiusura-wmf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id27_chiusura-wmf alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col,.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col{flex-direction:column;}.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column27_chiusura-wmf-col{position:relative;}@media all and (max-width: 1024px){.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column27_chiusura-wmf-col > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column27_chiusura-wmf-col\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#F6F2EC;font-size:clamp(20px, 2.5vw, 26px);font-style:italic;font-weight:300;line-height:1.6\">Stories travel.<br\/>Even when they remain within the pages of a book.<\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#C27A5A;margin-top:32px;font-size:13px;font-weight:500;letter-spacing:0.08em;text-transform:uppercase\"><a href=\"https:\/\/alchimianarrante.eu\/en\/linfermiera-del-respiro\/\" style=\"color:#C27A5A;text-decoration:none;border-bottom:1px solid #C27A5A;padding-bottom:2px\">Back to the book \u2192<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>L&#8217;infermiera del respiro Presentation at WMF 2026 Bologna, June 24\u201326, 2026 From June 24 to 26, 2026, &#8220;L&#8217;infermiera del respiro&#8221; was presented at the Web Marketing Festival in Bologna, one of Italy&#8217;s most popular events for those working with content, communication, and digital storytelling. An opportunity to share, outside the healthcare context, the value of&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":259,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-473","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/pages\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":2,"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/pages\/473\/revisions"}],"predecessor-version":[{"id":478,"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/pages\/473\/revisions\/478"}],"up":[{"embeddable":true,"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/pages\/259"}],"wp:attachment":[{"href":"https:\/\/alchimianarrante.eu\/en\/wp-json\/wp\/v2\/media?parent=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}